{"id":9495,"date":"2022-08-23T09:00:35","date_gmt":"2022-08-23T07:00:35","guid":{"rendered":"https:\/\/www.hinelson.com\/blog\/?p=9495"},"modified":"2022-09-30T13:13:50","modified_gmt":"2022-09-30T11:13:50","slug":"affondatore-idrodinamico-come-funziona","status":"publish","type":"post","link":"https:\/\/www.hinelson.com\/blog\/affondatore-idrodinamico-come-funziona\/","title":{"rendered":"Affondatore idrodinamico: come funziona?"},"content":{"rendered":"<p>Oggi parleremo dell&#8217;<a href=\"https:\/\/www.hinelson.com\/it\/653-affondatore-idrodinamico\"><strong>affondatore idrodinamico<\/strong><\/a>, un prezioso accessorio per la<a href=\"https:\/\/www.hinelson.com\/blog\/001-traina-veloce\/\"> pesca a traina<\/a>. Vedremo quindi come funziona questo accessorio, perch\u00e9 pu\u00f2 essere molto utile e quali sono le tipologie presenti in commercio, partendo dal presupposto che un affondatore idrodinamico, per quanto si tratti di uno strumento semplice ed economico, pu\u00f2 presentare differenti <strong>funzioni<\/strong>. Il presupposto di partenza in ogni caso \u00e8 uno: per diverse esigenze \u2013 per mirare a pesci che nuotano al di sotto la superficie e per mantenere lontane le varie lenze da pesca \u2013 il pescatore deve trovare un modo di affondare le esche durante la pesca a traina, il che senza un affondatore \u00e8 tutto fuorch\u00e9 banale.<\/p>\n<ul>\n<li><a href=\"#affondatore-idrodinamico\">Cos&#8217;\u00e8 l&#8217;affondatore idrodinamico? <\/a><\/li>\n<li><a href=\"#fai-da-te\">Affondatore idrodinamico fai da te <\/a><\/li>\n<li><a href=\"#scarpetta\">Quando usare la scarpetta<\/a><\/li>\n<li><a href=\"#scegliere\">Stonfo o scarpetta?<\/a><\/li>\n<\/ul>\n<h2 id=\"affondatore-idrodinamico\">Cos&#8217;\u00e8 l&#8217;affondatore idrodinamico?<\/h2>\n<p>Cos&#8217;\u00e8 l&#8217;affondatore idrodinamico e come funziona? Non sempre il pesce \u00e8 disposto a salire in <strong>superficie<\/strong>. Se non \u00e8 un problema per diverse tecniche di pesca, in cui il pescatore getta direttamente l&#8217;amo in profondit\u00e0, lo \u00e8 invece per la pesca a traina, quando le <a href=\"https:\/\/www.hinelson.com\/it\/427-esche-artificiali\">esche artificiali<\/a> di per s\u00e9 non riescono ad affondare in modo significativo, soprattutto a una certa <strong>velocit\u00e0<\/strong>. Entra quindi qui in gioco l&#8217;affondatore idrodinamico, un accessorio semplice quanto geniale. In commercio esistono degli esempi in <strong>plastica<\/strong> o in <strong>metallo<\/strong>, con forme o strutture diverse, nonch\u00e9 con nomi differenti, ufficiali e non (Stim, scarpetta, Stonfo e via dicendo).<br \/>\nL&#8217;affondatore per la pesca a traina va a sfruttare la trazione imposta dalla barca in movimento per guadagnare profondit\u00e0, cos\u00ec da andare a scovare i pesci che si rifiutano di salire in superficie. Ma non \u00e8 tutto qui: l&#8217;affondatore idrodinamico \u00e8 molto utile nel tipico caso di pi\u00f9 <a href=\"https:\/\/www.hinelson.com\/it\/424-canne-da-pesca\">canne da pesca<\/a> presenti, per andare ad aprire le lenze ed evitare che queste entrino in contatto tra loro. Proprio cos\u00ec: agendo sulle regolazioni degli affondatori idrodinamico pi\u00f9 completi \u00e8 infatti possibile variare non solo l&#8217;affondamento, ma anche la <strong>direzione<\/strong> dell&#8217;esca. Non parliamo di nulla di particolarmente difficile: basta variare il<strong> punto di attacco<\/strong> della lenza sul nostro affondatore per fare in modo che questo si disponga da una parte o dall&#8217;altra dello specchio di poppa.<br \/>\nLa funzione base, presente in tutti gli affondatori, \u00e8 quella di affondamento; come abbiamo visto, vi \u00e8 poi quella opzionale della regolazione laterale. C&#8217;\u00e8 peraltro una terza funzione, presente in tutti i modelli, che consente all&#8217;affondatore di mutare automaticamente assetto al momento dell&#8217;abboccata, trascinando in alto la preda e rendendo palese la cattura.<\/p>\n<h3 id=\"fai-da-te\">Affondatore idrodinamico fai da te<\/h3>\n<p>Ci sono, va detto, dei pescatori particolarmente pazienti e ingegnosi che hanno scelto di costruire con le proprie mani un<strong> affondatore artigianale<\/strong>, usando di volta in volta i pi\u00f9 diversi materiali di partenza, dai\u00a0<a href=\"https:\/\/www.hinelson.com\/it\/521-piombi-da-pesca\"><strong>piombi<\/strong><\/a> in poi. Una cosa \u00e8 per\u00f2 certa: visto il costo ridotto degli affondatori idrodinamici, e visti le regolazioni possibili sulle scarpette per la pesca a traina, nella maggior parte dei casi non vale la pena cimentarsi in tentativi di questo tipo. Tutto dipende per\u00f2 dalla propria voglia di sperimentare!<\/p>\n<h2 id=\"scarpetta\">Quando usare la scarpetta<\/h2>\n<p>In quali casi l&#8217;affondatore idrodinamico \u00e8 utile? Come anticipato, si parla della pesca a traina, una tecnica tutta particolare di <a href=\"https:\/\/www.hinelson.com\/blog\/pescare-in-barca-le-tecniche-per-iniziare\/\"><strong>pesca dalla barca<\/strong><\/a>. La scarpetta risulta utile nella normale traina <strong>leggera<\/strong> come nella traina <strong>notturna<\/strong> ai <strong>calamari<\/strong>.<\/p>\n<h2 id=\"scegliere\">Stonfo o scarpetta?<\/h2>\n<p>Esistono diverse tipologie di affondatori per la pesca a traina, di volta in volta con peculiarit\u00e0 e funzioni differenti. In linea di massima possiamo dire che tipicamente questi<strong> accessori per la pesca sportiva<\/strong> possono essere usati a <strong>velocit\u00e0 comprese tra i 2 e i 4 nodi<\/strong>, anche se va detto che alcuni modelli sono efficace fino a <strong>6 o 7 nodi di velocit\u00e0<\/strong>. La velocit\u00e0 di affondamento massima varia in base a tanti fattori, ma \u00e8 bene tenere come riferimento massimo una distanza dalla superficie pari a circa 15 metri (questo dato \u00e8 utile anche per evitare di<strong> toccare il fondo<\/strong>, con problemi di vario genere).<\/p>\n<h4>Affondatore Scarpetta<\/h4>\n<p>Presentiamo qui l&#8217;affondatore Scarpetta della <strong>Sele<\/strong>, un modello che riprende le forme dell&#8217;affondatore Stim. Si tratta di una scarpetta in plastica dura e bianca, in diverse misure disponibili e con differenti regolazioni, anche per avere una deriva verso destra o verso sinistra. Se trainato a una velocit\u00e0 fino a 2 nodi pu\u00f2 affondare di circa una decina di metri, mentre a velocit\u00e0 pi\u00f9 elevate tende a risalire verso la superficie: procedendo a 4 nodi si avr\u00e0 una profondit\u00e0 di circa 5 metri. Si tratta dello strumento ideale per un utilizzo insieme a <strong>cucchiaini<\/strong>, piccoli <strong>minnow<\/strong> e <strong>piumette<\/strong>.<\/p>\n<div class=\"clerk\" data-template=\"@blog-carosello-articoli-pesca\" data-keywords=\"ZA7107,ZA7108\"><\/div>\n<h4>Affondatore Stonfo<\/h4>\n<p>Pi\u00f9 strutturato \u00e8 l&#8217;affondatore idrodinamico della Stonfo. Qui \u00e8 presente infatti anche u<strong>n alettone mobile<\/strong> che permette di regolare facilmente la profondit\u00e0. Grazie alla sua forma pu\u00f2 essere usato anche 7 nodi, e quindi nella <strong>traina veloce<\/strong>. Anche in questo caso, va detto, si pu\u00f2 giocare sulla <strong>divergenza<\/strong>, legando l&#8217;affondatore idrodinamico da una parte o dall&#8217;altra.<\/p>\n<div class=\"clerk\" data-template=\"@blog-carosello-articoli-pesca\" data-keywords=\"ZA7114,ZA7113\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oggi parleremo dell&#8217;affondatore idrodinamico, un prezioso accessorio per la pesca a traina. Vedremo quindi come funziona questo accessorio, perch\u00e9 pu\u00f2 essere molto utile e quali sono le tipologie presenti in commercio, partendo dal presupposto che un affondatore idrodinamico, per quanto si tratti di uno strumento semplice ed economico, pu\u00f2 presentare differenti funzioni. Il presupposto di [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[334],"tags":[345,313,374,379,354],"class_list":{"0":"post-9495","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-guide-tutorial-nautica","8":"tag-guida-acquisto","9":"tag-how-to","10":"tag-tips-minuteria-accessori-pesca","11":"tag-tips-pesca-a-traina","12":"tag-pesca-sportiva"},"_links":{"self":[{"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/posts\/9495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/comments?post=9495"}],"version-history":[{"count":3,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/posts\/9495\/revisions"}],"predecessor-version":[{"id":9500,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/posts\/9495\/revisions\/9500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/media\/9496"}],"wp:attachment":[{"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/media?parent=9495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/categories?post=9495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hinelson.com\/blog\/wp-json\/wp\/v2\/tags?post=9495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}